{"id":230,"date":"2021-07-14T23:09:20","date_gmt":"2021-07-14T21:09:20","guid":{"rendered":"https:\/\/chrassi.de\/?p=230"},"modified":"2021-08-07T18:15:59","modified_gmt":"2021-08-07T16:15:59","slug":"wald-wald-storche-bisons","status":"publish","type":"post","link":"https:\/\/chrassi.de\/index.php\/2021\/07\/14\/wald-wald-storche-bisons\/","title":{"rendered":"Wald, Wald,  Storche ( &#038; Bisons)"},"content":{"rendered":"\n<p class=\"has-medium-font-size\"><strong>BIALOWIEZA<\/strong><\/p>\n\n\n\n<p>Nachdem wir Vilnius fluchtartig verlassen hatten, betreten wir nun das sch\u00f6ne Gebiet rund um den ber\u00fchmten Nationalpark Bialowieza. Ber\u00fchmt deshalb, weil es hier den einzig verbliebenen von Menschen g\u00e4nzlich unber\u00fchrten Rest Urwalds in Europa gibt. Leider liegt der weit gr\u00f6\u00dfere Teil davon in Belarus, aufgrund der Oppression durch Lukaschenko und der damit einhergehenden dichten Grenzen also unerreichbar f\u00fcr uns ( und alle anderen). <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/chrassi.de\/wp-content\/uploads\/C714A673-7C3C-4DF6-9915-D8415B5821D0-1024x683.jpeg\" alt=\"\" class=\"wp-image-231\" srcset=\"https:\/\/chrassi.de\/wp-content\/uploads\/C714A673-7C3C-4DF6-9915-D8415B5821D0-1024x683.jpeg 1024w, https:\/\/chrassi.de\/wp-content\/uploads\/C714A673-7C3C-4DF6-9915-D8415B5821D0-300x200.jpeg 300w, https:\/\/chrassi.de\/wp-content\/uploads\/C714A673-7C3C-4DF6-9915-D8415B5821D0-768x512.jpeg 768w, https:\/\/chrassi.de\/wp-content\/uploads\/C714A673-7C3C-4DF6-9915-D8415B5821D0-1536x1024.jpeg 1536w, https:\/\/chrassi.de\/wp-content\/uploads\/C714A673-7C3C-4DF6-9915-D8415B5821D0-2048x1365.jpeg 2048w, https:\/\/chrassi.de\/wp-content\/uploads\/C714A673-7C3C-4DF6-9915-D8415B5821D0-1140x760.jpeg 1140w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Kleine Deadmanfingers in Moos und Klee \u2618\ufe0f\ud83c\udf44\ud83c\udf31<\/figcaption><\/figure>\n\n\n\n<p>Das Dorf Bialowieza selbst hat mir total gut gefallen; \u00fcbersichtlich, friedlich, mit  niedlichen Holzh\u00e4usern und vor allem h\u00fcbschen Campingpl\u00e4tzen inmitten all der Storchis in Nestern oder auf dem Feld staksend!  Zwischen tragenden Beerenstr\u00e4uchern und Sauerkirschb\u00e4umchen zu stehen hat mir auch getaugt \ud83d\ude1b <\/p>\n\n\n\n<p>Nat\u00fcrlich haben wir an einer Tour durch den Nationalpark teil genommen, bestehend aus einem sportlichen 4h Spaziergang mit Joanna, unserer Guide. Wie auch all die anderen \u00fcber 200 Guides* dort ist sie Biologin und konnte wirklich zu jedem Pilz, jedem toten oder lebenden Baum und auch zu verschiedenen Tierspuren nicht nur etwas, sondern ganz viel erz\u00e4hlen. Das war schon sehr interessant und sie als Person auch wirklich mit Leidenschaft dabei. Fakt ist allerdings auch, dass dieser Urwald am Ende des Tages eben doch auch \u201enur\u201c ziemlicher alter europ\u00e4ischer Wald mit haupts\u00e4chlich ( relativ gro\u00dfen) Eichen und Buchen ist. Ich muss gestehen, dass mir da auf den ersten Blick keine gro\u00dfen Unterschiede zu einem herk\u00f6mmlichen Wald aufgefallen w\u00e4ren, zumindest ohne die Erl\u00e4uterungen und ohne hinauf in die Wipfel zu schauen!<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/chrassi.de\/wp-content\/uploads\/489BDE22-29E8-43C7-A8A7-6A5FDD519A01-576x1024.jpeg\" alt=\"\" data-id=\"234\" data-link=\"https:\/\/chrassi.de\/?attachment_id=234\" class=\"wp-image-234\" srcset=\"https:\/\/chrassi.de\/wp-content\/uploads\/489BDE22-29E8-43C7-A8A7-6A5FDD519A01-576x1024.jpeg 576w, https:\/\/chrassi.de\/wp-content\/uploads\/489BDE22-29E8-43C7-A8A7-6A5FDD519A01-169x300.jpeg 169w, https:\/\/chrassi.de\/wp-content\/uploads\/489BDE22-29E8-43C7-A8A7-6A5FDD519A01-768x1365.jpeg 768w, https:\/\/chrassi.de\/wp-content\/uploads\/489BDE22-29E8-43C7-A8A7-6A5FDD519A01-864x1536.jpeg 864w, https:\/\/chrassi.de\/wp-content\/uploads\/489BDE22-29E8-43C7-A8A7-6A5FDD519A01-1152x2048.jpeg 1152w, https:\/\/chrassi.de\/wp-content\/uploads\/489BDE22-29E8-43C7-A8A7-6A5FDD519A01-1140x2027.jpeg 1140w, https:\/\/chrassi.de\/wp-content\/uploads\/489BDE22-29E8-43C7-A8A7-6A5FDD519A01-scaled.jpeg 1440w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><figcaption class=\"blocks-gallery-item__caption\">Die eigt ganz h\u00fcbsch anmutenden G\u00e4nge des Borkenk\u00e4fers in der Baumrinde an diesem St\u00fcck gut zu sehen<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/chrassi.de\/wp-content\/uploads\/6EBCF119-1DF3-4033-8F66-3FB1E5AE5834-1024x683.jpeg\" alt=\"\" data-id=\"236\" data-full-url=\"https:\/\/chrassi.de\/wp-content\/uploads\/6EBCF119-1DF3-4033-8F66-3FB1E5AE5834-scaled.jpeg\" data-link=\"https:\/\/chrassi.de\/?attachment_id=236\" class=\"wp-image-236\" srcset=\"https:\/\/chrassi.de\/wp-content\/uploads\/6EBCF119-1DF3-4033-8F66-3FB1E5AE5834-1024x683.jpeg 1024w, https:\/\/chrassi.de\/wp-content\/uploads\/6EBCF119-1DF3-4033-8F66-3FB1E5AE5834-300x200.jpeg 300w, https:\/\/chrassi.de\/wp-content\/uploads\/6EBCF119-1DF3-4033-8F66-3FB1E5AE5834-768x512.jpeg 768w, https:\/\/chrassi.de\/wp-content\/uploads\/6EBCF119-1DF3-4033-8F66-3FB1E5AE5834-1536x1024.jpeg 1536w, https:\/\/chrassi.de\/wp-content\/uploads\/6EBCF119-1DF3-4033-8F66-3FB1E5AE5834-2048x1365.jpeg 2048w, https:\/\/chrassi.de\/wp-content\/uploads\/6EBCF119-1DF3-4033-8F66-3FB1E5AE5834-1140x760.jpeg 1140w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"blocks-gallery-item__caption\">Blick in die hohen Baumkronen der uralten B\u00e4ume<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/chrassi.de\/wp-content\/uploads\/25B4AD30-BC82-4564-A6EA-05EBE8457FBA-1024x683.jpeg\" alt=\"\" data-id=\"237\" data-full-url=\"https:\/\/chrassi.de\/wp-content\/uploads\/25B4AD30-BC82-4564-A6EA-05EBE8457FBA-scaled.jpeg\" data-link=\"https:\/\/chrassi.de\/?attachment_id=237\" class=\"wp-image-237\" srcset=\"https:\/\/chrassi.de\/wp-content\/uploads\/25B4AD30-BC82-4564-A6EA-05EBE8457FBA-1024x683.jpeg 1024w, https:\/\/chrassi.de\/wp-content\/uploads\/25B4AD30-BC82-4564-A6EA-05EBE8457FBA-300x200.jpeg 300w, https:\/\/chrassi.de\/wp-content\/uploads\/25B4AD30-BC82-4564-A6EA-05EBE8457FBA-768x512.jpeg 768w, https:\/\/chrassi.de\/wp-content\/uploads\/25B4AD30-BC82-4564-A6EA-05EBE8457FBA-1536x1024.jpeg 1536w, https:\/\/chrassi.de\/wp-content\/uploads\/25B4AD30-BC82-4564-A6EA-05EBE8457FBA-2048x1365.jpeg 2048w, https:\/\/chrassi.de\/wp-content\/uploads\/25B4AD30-BC82-4564-A6EA-05EBE8457FBA-1140x760.jpeg 1140w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"blocks-gallery-item__caption\">Eine vermutlich um die 400 Jahre alte Eiche<\/figcaption><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>Im Bialowieza Wald gibt es zwar auch Tiere wie vor allem Bisons, W\u00f6lfe und Luchse, man muss allerdings schon wirklich Gl\u00fcck haben einen Blick auf diese erhaschen zu k\u00f6nnen. Bei einer der early-morning-tours ist die Wahrscheinlichkeit dann wohl etwas h\u00f6her. Der Bison ist aber unverkennbar das Wahrzeichen von Bialowieza, \u00fcberall wird ihm gehuldigt, es gibt eine Bisonfarm und sogar eine \u00f6rtliche Brauerei mit Bisonwappen. Chris hat deren Bier hier frisch f\u00fcr Euch getestet:<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/chrassi.de\/wp-content\/uploads\/BE41C5CD-A421-430C-AB89-25F56E767B15-576x1024.jpeg\" alt=\"\" data-id=\"238\" data-link=\"https:\/\/chrassi.de\/?attachment_id=238\" class=\"wp-image-238\" srcset=\"https:\/\/chrassi.de\/wp-content\/uploads\/BE41C5CD-A421-430C-AB89-25F56E767B15-576x1024.jpeg 576w, https:\/\/chrassi.de\/wp-content\/uploads\/BE41C5CD-A421-430C-AB89-25F56E767B15-169x300.jpeg 169w, https:\/\/chrassi.de\/wp-content\/uploads\/BE41C5CD-A421-430C-AB89-25F56E767B15-768x1365.jpeg 768w, https:\/\/chrassi.de\/wp-content\/uploads\/BE41C5CD-A421-430C-AB89-25F56E767B15-864x1536.jpeg 864w, https:\/\/chrassi.de\/wp-content\/uploads\/BE41C5CD-A421-430C-AB89-25F56E767B15-1152x2048.jpeg 1152w, https:\/\/chrassi.de\/wp-content\/uploads\/BE41C5CD-A421-430C-AB89-25F56E767B15-1140x2027.jpeg 1140w, https:\/\/chrassi.de\/wp-content\/uploads\/BE41C5CD-A421-430C-AB89-25F56E767B15-scaled.jpeg 1440w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><figcaption class=\"blocks-gallery-item__caption\">Ein wahrer Genuss<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/chrassi.de\/wp-content\/uploads\/D82B8B56-22D9-4CE5-9116-2CB2941B4B25-576x1024.jpeg\" alt=\"\" data-id=\"239\" data-link=\"https:\/\/chrassi.de\/?attachment_id=239\" class=\"wp-image-239\" srcset=\"https:\/\/chrassi.de\/wp-content\/uploads\/D82B8B56-22D9-4CE5-9116-2CB2941B4B25-576x1024.jpeg 576w, https:\/\/chrassi.de\/wp-content\/uploads\/D82B8B56-22D9-4CE5-9116-2CB2941B4B25-169x300.jpeg 169w, https:\/\/chrassi.de\/wp-content\/uploads\/D82B8B56-22D9-4CE5-9116-2CB2941B4B25-768x1365.jpeg 768w, https:\/\/chrassi.de\/wp-content\/uploads\/D82B8B56-22D9-4CE5-9116-2CB2941B4B25-864x1536.jpeg 864w, https:\/\/chrassi.de\/wp-content\/uploads\/D82B8B56-22D9-4CE5-9116-2CB2941B4B25-1152x2048.jpeg 1152w, https:\/\/chrassi.de\/wp-content\/uploads\/D82B8B56-22D9-4CE5-9116-2CB2941B4B25-1140x2027.jpeg 1140w, https:\/\/chrassi.de\/wp-content\/uploads\/D82B8B56-22D9-4CE5-9116-2CB2941B4B25-scaled.jpeg 1440w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><figcaption class=\"blocks-gallery-item__caption\">in drei<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/chrassi.de\/wp-content\/uploads\/959FF6DA-DA72-4C1B-8261-85DB186E7C41-576x1024.jpeg\" alt=\"\" data-id=\"240\" data-link=\"https:\/\/chrassi.de\/?attachment_id=240\" class=\"wp-image-240\" srcset=\"https:\/\/chrassi.de\/wp-content\/uploads\/959FF6DA-DA72-4C1B-8261-85DB186E7C41-576x1024.jpeg 576w, https:\/\/chrassi.de\/wp-content\/uploads\/959FF6DA-DA72-4C1B-8261-85DB186E7C41-169x300.jpeg 169w, https:\/\/chrassi.de\/wp-content\/uploads\/959FF6DA-DA72-4C1B-8261-85DB186E7C41-768x1365.jpeg 768w, https:\/\/chrassi.de\/wp-content\/uploads\/959FF6DA-DA72-4C1B-8261-85DB186E7C41-864x1536.jpeg 864w, https:\/\/chrassi.de\/wp-content\/uploads\/959FF6DA-DA72-4C1B-8261-85DB186E7C41-1152x2048.jpeg 1152w, https:\/\/chrassi.de\/wp-content\/uploads\/959FF6DA-DA72-4C1B-8261-85DB186E7C41-1140x2027.jpeg 1140w, https:\/\/chrassi.de\/wp-content\/uploads\/959FF6DA-DA72-4C1B-8261-85DB186E7C41-scaled.jpeg 1440w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><figcaption class=\"blocks-gallery-item__caption\">Akten \ud83d\ude09<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/chrassi.de\/wp-content\/uploads\/8B4B7EAA-0DDC-4503-AEF3-CA2CEA1A2CFA-576x1024.jpeg\" alt=\"\" data-id=\"242\" data-full-url=\"https:\/\/chrassi.de\/wp-content\/uploads\/8B4B7EAA-0DDC-4503-AEF3-CA2CEA1A2CFA-scaled.jpeg\" data-link=\"https:\/\/chrassi.de\/?attachment_id=242\" class=\"wp-image-242\" srcset=\"https:\/\/chrassi.de\/wp-content\/uploads\/8B4B7EAA-0DDC-4503-AEF3-CA2CEA1A2CFA-576x1024.jpeg 576w, https:\/\/chrassi.de\/wp-content\/uploads\/8B4B7EAA-0DDC-4503-AEF3-CA2CEA1A2CFA-169x300.jpeg 169w, https:\/\/chrassi.de\/wp-content\/uploads\/8B4B7EAA-0DDC-4503-AEF3-CA2CEA1A2CFA-768x1365.jpeg 768w, https:\/\/chrassi.de\/wp-content\/uploads\/8B4B7EAA-0DDC-4503-AEF3-CA2CEA1A2CFA-864x1536.jpeg 864w, https:\/\/chrassi.de\/wp-content\/uploads\/8B4B7EAA-0DDC-4503-AEF3-CA2CEA1A2CFA-1152x2048.jpeg 1152w, https:\/\/chrassi.de\/wp-content\/uploads\/8B4B7EAA-0DDC-4503-AEF3-CA2CEA1A2CFA-1140x2027.jpeg 1140w, https:\/\/chrassi.de\/wp-content\/uploads\/8B4B7EAA-0DDC-4503-AEF3-CA2CEA1A2CFA-scaled.jpeg 1440w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><figcaption class=\"blocks-gallery-item__caption\">Und hier sogar nochmal mit Storchis !<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/chrassi.de\/wp-content\/uploads\/693ECDDB-33B4-4026-821A-43A5D7D91B49-1024x576.jpeg\" alt=\"\" data-id=\"243\" data-full-url=\"https:\/\/chrassi.de\/wp-content\/uploads\/693ECDDB-33B4-4026-821A-43A5D7D91B49-scaled.jpeg\" data-link=\"https:\/\/chrassi.de\/?attachment_id=243\" class=\"wp-image-243\" srcset=\"https:\/\/chrassi.de\/wp-content\/uploads\/693ECDDB-33B4-4026-821A-43A5D7D91B49-1024x576.jpeg 1024w, https:\/\/chrassi.de\/wp-content\/uploads\/693ECDDB-33B4-4026-821A-43A5D7D91B49-300x169.jpeg 300w, https:\/\/chrassi.de\/wp-content\/uploads\/693ECDDB-33B4-4026-821A-43A5D7D91B49-768x432.jpeg 768w, https:\/\/chrassi.de\/wp-content\/uploads\/693ECDDB-33B4-4026-821A-43A5D7D91B49-1536x864.jpeg 1536w, https:\/\/chrassi.de\/wp-content\/uploads\/693ECDDB-33B4-4026-821A-43A5D7D91B49-2048x1152.jpeg 2048w, https:\/\/chrassi.de\/wp-content\/uploads\/693ECDDB-33B4-4026-821A-43A5D7D91B49-1140x641.jpeg 1140w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"blocks-gallery-item__caption\">Omnom frische Blinis mit Hering und auch K\u00e4se gabs auch noch<\/figcaption><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>Wir haben aber nicht nur den ber\u00fchmten Urwald besichtigt, sondern haben uns mit komoot auch eine sch\u00f6ne Tour rausgesucht und uns auf die R\u00e4der geschwungen um das umliegende Naturschutzgebiet auf diesem Wege noch ein bisschen zu erkunden. Bin sehr froh die R\u00e4der auf unserer Reise dabei zu haben, wir haben sie bisher bei fast jedem unserer Stopps entweder f\u00fcr Besorgungen, Stadterkundungen oder f\u00fcr sportliche Touren genutzt.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/chrassi.de\/wp-content\/uploads\/6DD8179C-3147-42F7-B4BF-7236C4147180-1024x576.jpeg\" alt=\"\" data-id=\"249\" data-full-url=\"https:\/\/chrassi.de\/wp-content\/uploads\/6DD8179C-3147-42F7-B4BF-7236C4147180-scaled.jpeg\" data-link=\"https:\/\/chrassi.de\/?attachment_id=249\" class=\"wp-image-249\" srcset=\"https:\/\/chrassi.de\/wp-content\/uploads\/6DD8179C-3147-42F7-B4BF-7236C4147180-1024x576.jpeg 1024w, https:\/\/chrassi.de\/wp-content\/uploads\/6DD8179C-3147-42F7-B4BF-7236C4147180-300x169.jpeg 300w, https:\/\/chrassi.de\/wp-content\/uploads\/6DD8179C-3147-42F7-B4BF-7236C4147180-768x432.jpeg 768w, https:\/\/chrassi.de\/wp-content\/uploads\/6DD8179C-3147-42F7-B4BF-7236C4147180-1536x864.jpeg 1536w, https:\/\/chrassi.de\/wp-content\/uploads\/6DD8179C-3147-42F7-B4BF-7236C4147180-2048x1152.jpeg 2048w, https:\/\/chrassi.de\/wp-content\/uploads\/6DD8179C-3147-42F7-B4BF-7236C4147180-1140x641.jpeg 1140w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/chrassi.de\/wp-content\/uploads\/87C93276-F725-43AB-BA52-A5370F419C68-1024x576.jpeg\" alt=\"\" data-id=\"248\" data-full-url=\"https:\/\/chrassi.de\/wp-content\/uploads\/87C93276-F725-43AB-BA52-A5370F419C68-scaled.jpeg\" data-link=\"https:\/\/chrassi.de\/?attachment_id=248\" class=\"wp-image-248\" srcset=\"https:\/\/chrassi.de\/wp-content\/uploads\/87C93276-F725-43AB-BA52-A5370F419C68-1024x576.jpeg 1024w, https:\/\/chrassi.de\/wp-content\/uploads\/87C93276-F725-43AB-BA52-A5370F419C68-300x169.jpeg 300w, https:\/\/chrassi.de\/wp-content\/uploads\/87C93276-F725-43AB-BA52-A5370F419C68-768x432.jpeg 768w, https:\/\/chrassi.de\/wp-content\/uploads\/87C93276-F725-43AB-BA52-A5370F419C68-1536x864.jpeg 1536w, https:\/\/chrassi.de\/wp-content\/uploads\/87C93276-F725-43AB-BA52-A5370F419C68-2048x1152.jpeg 2048w, https:\/\/chrassi.de\/wp-content\/uploads\/87C93276-F725-43AB-BA52-A5370F419C68-1140x641.jpeg 1140w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>Am zweiten Tag haben wir auch eine Kajaktour, bei einem unendlich chilligen Kajakverleih startend, unternommen. Die Tour kam inmitten des Naturschutzgebiets und mit den sch\u00f6nen Seerosen etc so romantisch daher, entpuppte sich dann aber ganz schnell als fieser Hinterhalt aller Bremsen die Bialowieza zu bieten hatte!! Funktionierender Artenschutz, ough so nervig. Bewirkt hat die Hetzjagd auf uns, dass wir gen\u00f6tigt waren richtig schnell zu paddeln \ud83d\ude00 Ca 30 Bremsen mussten dann aber doch weggeklatscht werden, is wies is.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/chrassi.de\/wp-content\/uploads\/69AEA92E-BB4F-4D93-9F90-A999D77314A0-576x1024.jpeg\" alt=\"\" data-id=\"253\" data-full-url=\"https:\/\/chrassi.de\/wp-content\/uploads\/69AEA92E-BB4F-4D93-9F90-A999D77314A0-scaled.jpeg\" data-link=\"https:\/\/chrassi.de\/?attachment_id=253\" class=\"wp-image-253\" srcset=\"https:\/\/chrassi.de\/wp-content\/uploads\/69AEA92E-BB4F-4D93-9F90-A999D77314A0-576x1024.jpeg 576w, https:\/\/chrassi.de\/wp-content\/uploads\/69AEA92E-BB4F-4D93-9F90-A999D77314A0-169x300.jpeg 169w, https:\/\/chrassi.de\/wp-content\/uploads\/69AEA92E-BB4F-4D93-9F90-A999D77314A0-768x1365.jpeg 768w, https:\/\/chrassi.de\/wp-content\/uploads\/69AEA92E-BB4F-4D93-9F90-A999D77314A0-864x1536.jpeg 864w, https:\/\/chrassi.de\/wp-content\/uploads\/69AEA92E-BB4F-4D93-9F90-A999D77314A0-1152x2048.jpeg 1152w, https:\/\/chrassi.de\/wp-content\/uploads\/69AEA92E-BB4F-4D93-9F90-A999D77314A0-1140x2027.jpeg 1140w, https:\/\/chrassi.de\/wp-content\/uploads\/69AEA92E-BB4F-4D93-9F90-A999D77314A0-scaled.jpeg 1440w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><figcaption class=\"blocks-gallery-item__caption\">Sour-beer mit Maracuja, einfach geiles Sommergetr\u00e4nk<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"485\" height=\"1024\" src=\"https:\/\/chrassi.de\/wp-content\/uploads\/705A72A0-A21A-4864-B255-1C0F587AE44D-485x1024.jpeg\" alt=\"\" data-id=\"251\" data-full-url=\"https:\/\/chrassi.de\/wp-content\/uploads\/705A72A0-A21A-4864-B255-1C0F587AE44D.jpeg\" data-link=\"https:\/\/chrassi.de\/?attachment_id=251\" class=\"wp-image-251\" srcset=\"https:\/\/chrassi.de\/wp-content\/uploads\/705A72A0-A21A-4864-B255-1C0F587AE44D-485x1024.jpeg 485w, https:\/\/chrassi.de\/wp-content\/uploads\/705A72A0-A21A-4864-B255-1C0F587AE44D-142x300.jpeg 142w, https:\/\/chrassi.de\/wp-content\/uploads\/705A72A0-A21A-4864-B255-1C0F587AE44D-768x1623.jpeg 768w, https:\/\/chrassi.de\/wp-content\/uploads\/705A72A0-A21A-4864-B255-1C0F587AE44D-727x1536.jpeg 727w, https:\/\/chrassi.de\/wp-content\/uploads\/705A72A0-A21A-4864-B255-1C0F587AE44D.jpeg 969w\" sizes=\"auto, (max-width: 485px) 100vw, 485px\" \/><figcaption class=\"blocks-gallery-item__caption\">eine kleine Auswahl erlegter Bremsen<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"486\" height=\"1024\" src=\"https:\/\/chrassi.de\/wp-content\/uploads\/9E2C5DC8-61E7-4E6A-84F4-42E8DBA81784-486x1024.jpeg\" alt=\"\" data-id=\"252\" data-full-url=\"https:\/\/chrassi.de\/wp-content\/uploads\/9E2C5DC8-61E7-4E6A-84F4-42E8DBA81784.jpeg\" data-link=\"https:\/\/chrassi.de\/?attachment_id=252\" class=\"wp-image-252\" srcset=\"https:\/\/chrassi.de\/wp-content\/uploads\/9E2C5DC8-61E7-4E6A-84F4-42E8DBA81784-486x1024.jpeg 486w, https:\/\/chrassi.de\/wp-content\/uploads\/9E2C5DC8-61E7-4E6A-84F4-42E8DBA81784-142x300.jpeg 142w, https:\/\/chrassi.de\/wp-content\/uploads\/9E2C5DC8-61E7-4E6A-84F4-42E8DBA81784-768x1620.jpeg 768w, https:\/\/chrassi.de\/wp-content\/uploads\/9E2C5DC8-61E7-4E6A-84F4-42E8DBA81784-728x1536.jpeg 728w, https:\/\/chrassi.de\/wp-content\/uploads\/9E2C5DC8-61E7-4E6A-84F4-42E8DBA81784.jpeg 971w\" sizes=\"auto, (max-width: 486px) 100vw, 486px\" \/><figcaption class=\"blocks-gallery-item__caption\">Immer muss die Frau die ganze Arbeit machen \ud83d\ude21<\/figcaption><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>Fazit von Bialowieza: Sch\u00f6nes Naturschutzgebiet, extra nur f\u00fcr den Nationalpark dort hin fahren w\u00fcrde ich pers\u00f6nlich nicht unbedingt, bei einer Durchreise von Polen sollte das aber auf jeden Fall eingeplant werden! ( hallo es gibt dort \u00fcberall Bebistorchis und Bisons)<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>AUSCHWITZ-BIRKENAU<\/strong><\/p>\n\n\n\n<p>Damit komme ich nun aber zu einem sehr d\u00fcsteren  Punkt unserer Polendurchquerung, der meiner Meinung nach aber auf jeden Fall zum Pflichtprogramm dazu geh\u00f6rt&#8230; Zumindest dann, wenn man noch nie vorher eine Gedenkst\u00e4tte des Holocausts besucht hat, was zumindest auf mich zutraf. Ich war davor auch leicht nerv\u00f6s, denn es ist klar dass ein Besuch in Auschwitz- Birkenau in jedem Fall belastend wird. Ich habe w\u00e4hrend des 3,5 st\u00fcndigen Rundgangs durch Auschwitz 1 und Auschwitz 2 mehrmals dar\u00fcber nachgedacht, ob wir das als Nachfahren der T\u00e4ter mit einem anderen Blickwinkel des Grauens und der Demut erleben als Menschen anderer Nationalit\u00e4ten. Ich vermute schon. Jedenfalls ging es mir sehr nahe und der Anblick der abertausenden auf gigantischen Bergen gesammelten und ausgestellten Originalgegenst\u00e4nde hinter den Glasfronten der haupts\u00e4chlich J\u00fcdinnen und Juden und der Modellnachbau der Gaskammern und Krematorien war nur sehr schwer zu ertragen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/chrassi.de\/wp-content\/uploads\/63365424-9BF3-4BB1-84C3-20458744807F-1024x576.jpeg\" alt=\"\" class=\"wp-image-257\" srcset=\"https:\/\/chrassi.de\/wp-content\/uploads\/63365424-9BF3-4BB1-84C3-20458744807F-1024x576.jpeg 1024w, https:\/\/chrassi.de\/wp-content\/uploads\/63365424-9BF3-4BB1-84C3-20458744807F-300x169.jpeg 300w, https:\/\/chrassi.de\/wp-content\/uploads\/63365424-9BF3-4BB1-84C3-20458744807F-768x432.jpeg 768w, https:\/\/chrassi.de\/wp-content\/uploads\/63365424-9BF3-4BB1-84C3-20458744807F-1536x864.jpeg 1536w, https:\/\/chrassi.de\/wp-content\/uploads\/63365424-9BF3-4BB1-84C3-20458744807F-2048x1152.jpeg 2048w, https:\/\/chrassi.de\/wp-content\/uploads\/63365424-9BF3-4BB1-84C3-20458744807F-1140x641.jpeg 1140w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Nat\u00fcrlich hab ich das meiste geschichtliche gewusst, aber manche verst\u00f6rende Details waren dennoch neu f\u00fcr mich. Mir war nicht klar, dass das KL Auschwitz 1 ( also das im Allgemeinen bekannteste KL) wie auf obiger Karte gut sichtbar verh\u00e4ltnism\u00e4\u00dfig klein war. Und das schlimme dabei ist, dass man aber nicht das Gef\u00fchl hat wenn man dort von Block zu Block l\u00e4uft. Es wirkt eher sehr weitl\u00e4ufig und gro\u00df. Dann sieht man dass Auschwitz 2- Birkenau in der N\u00e4he ungef\u00e4hr 20mal so gro\u00df ist. Und man realisiert, dass das gemeinhin bekannte Auschwitz 1 ein Konzentrationslager war, Birkenau jedoch ein reines Vernichtungslager.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"750\" src=\"https:\/\/chrassi.de\/wp-content\/uploads\/E3069BCA-E3E5-40D0-AA48-8D506D9E1B64-1024x750.jpeg\" alt=\"\" class=\"wp-image-259\" srcset=\"https:\/\/chrassi.de\/wp-content\/uploads\/E3069BCA-E3E5-40D0-AA48-8D506D9E1B64-1024x750.jpeg 1024w, https:\/\/chrassi.de\/wp-content\/uploads\/E3069BCA-E3E5-40D0-AA48-8D506D9E1B64-300x220.jpeg 300w, https:\/\/chrassi.de\/wp-content\/uploads\/E3069BCA-E3E5-40D0-AA48-8D506D9E1B64-768x563.jpeg 768w, https:\/\/chrassi.de\/wp-content\/uploads\/E3069BCA-E3E5-40D0-AA48-8D506D9E1B64-1536x1126.jpeg 1536w, https:\/\/chrassi.de\/wp-content\/uploads\/E3069BCA-E3E5-40D0-AA48-8D506D9E1B64-2048x1501.jpeg 2048w, https:\/\/chrassi.de\/wp-content\/uploads\/E3069BCA-E3E5-40D0-AA48-8D506D9E1B64-1140x835.jpeg 1140w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>In beiden KL wurden zwischen 1941 und 1944 1,5 Millionen Menschen ermordet, haupts\u00e4chlich J\u00fcdinnen und Juden aus diesen Teilen Europas. Man erkennt weshalb die Nazis den Ort O\u015bwi\u0119cim gew\u00e4hlt haben. <\/p>\n\n\n\n<p>Noch w\u00e4hrend wir an den Ruinen der Gaskammern und  Krematorien Birkenaus vorbeilaufen erreicht uns die Nachricht, dass die Auschwitz\u00fcberlebende Esther Bejarano heute mit 96 Jahren gestorben ist und ich glaube trauriger wird es auf unserer Reise nicht mehr.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"875\" height=\"1024\" src=\"https:\/\/chrassi.de\/wp-content\/uploads\/B432AFA3-8122-4145-997F-92CAFDE0A0E5-875x1024.jpeg\" alt=\"\" class=\"wp-image-264\" srcset=\"https:\/\/chrassi.de\/wp-content\/uploads\/B432AFA3-8122-4145-997F-92CAFDE0A0E5-875x1024.jpeg 875w, https:\/\/chrassi.de\/wp-content\/uploads\/B432AFA3-8122-4145-997F-92CAFDE0A0E5-256x300.jpeg 256w, https:\/\/chrassi.de\/wp-content\/uploads\/B432AFA3-8122-4145-997F-92CAFDE0A0E5-768x899.jpeg 768w, https:\/\/chrassi.de\/wp-content\/uploads\/B432AFA3-8122-4145-997F-92CAFDE0A0E5-1313x1536.jpeg 1313w, https:\/\/chrassi.de\/wp-content\/uploads\/B432AFA3-8122-4145-997F-92CAFDE0A0E5-1750x2048.jpeg 1750w, https:\/\/chrassi.de\/wp-content\/uploads\/B432AFA3-8122-4145-997F-92CAFDE0A0E5-1140x1334.jpeg 1140w\" sizes=\"auto, (max-width: 875px) 100vw, 875px\" \/><\/figure>\n\n\n\n<p>Weiter f\u00fchrt uns unsere  Reise in die <a href=\"https:\/\/chrassi.de\/index.php\/2021\/07\/18\/slowakei-in-der-schnellwanderung\/\" data-type=\"URL\" data-id=\"https:\/\/chrassi.de\/index.php\/2021\/07\/18\/slowakei-in-der-schnellwanderung\/\">Slowakei<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>BIALOWIEZA Nachdem wir Vilnius fluchtartig verlassen hatten, betreten wir nun das sch\u00f6ne Gebiet rund um den ber\u00fchmten Nationalpark Bialowieza. Ber\u00fchmt deshalb, weil es hier den einzig verbliebenen von Menschen g\u00e4nzlich unber\u00fchrten Rest Urwalds in Europa gibt. Leider liegt der weit gr\u00f6\u00dfere Teil davon in Belarus, aufgrund der Oppression durch Lukaschenko und der damit einhergehenden dichten Grenzen also unerreichbar f\u00fcr uns ( und alle anderen). Das Dorf Bialowieza selbst hat mir total gut gefallen; \u00fcbersichtlich, friedlich, mit niedlichen Holzh\u00e4usern und vor allem h\u00fcbschen Campingpl\u00e4tzen inmitten all der Storchis in Nestern oder auf dem Feld staksend! Zwischen tragenden Beerenstr\u00e4uchern und Sauerkirschb\u00e4umchen zu stehen hat mir auch getaugt \ud83d\ude1b Nat\u00fcrlich haben wir an einer Tour durch den Nationalpark teil genommen, bestehend aus einem sportlichen 4h Spaziergang mit Joanna, unserer Guide. Wie auch all die anderen \u00fcber 200 Guides* dort ist sie Biologin und konnte wirklich zu jedem Pilz, jedem toten oder lebenden Baum und auch zu verschiedenen Tierspuren nicht nur etwas, sondern ganz viel erz\u00e4hlen. Das war schon sehr interessant und sie als Person auch wirklich mit Leidenschaft dabei. Fakt ist allerdings auch, dass dieser Urwald am Ende des Tages eben doch auch \u201enur\u201c ziemlicher alter europ\u00e4ischer Wald mit haupts\u00e4chlich ( relativ gro\u00dfen) Eichen und Buchen ist. Ich muss gestehen, dass mir da auf den ersten Blick keine gro\u00dfen Unterschiede zu einem herk\u00f6mmlichen Wald aufgefallen w\u00e4ren, zumindest ohne die Erl\u00e4uterungen und ohne hinauf in die Wipfel zu schauen! Im Bialowieza Wald gibt es zwar auch Tiere wie vor allem Bisons, W\u00f6lfe und Luchse, man muss allerdings schon wirklich Gl\u00fcck haben einen Blick auf diese erhaschen zu k\u00f6nnen. Bei einer der early-morning-tours ist die Wahrscheinlichkeit dann wohl etwas h\u00f6her. Der Bison ist aber unverkennbar das Wahrzeichen von Bialowieza, \u00fcberall wird ihm gehuldigt, es gibt eine Bisonfarm und sogar eine \u00f6rtliche Brauerei mit Bisonwappen. Chris hat deren Bier hier frisch f\u00fcr Euch getestet: Wir haben aber nicht nur den ber\u00fchmten Urwald besichtigt, sondern haben uns mit komoot auch eine sch\u00f6ne Tour rausgesucht und uns auf die R\u00e4der geschwungen um das umliegende Naturschutzgebiet auf diesem Wege noch ein bisschen zu erkunden. Bin sehr froh die R\u00e4der auf unserer Reise dabei zu haben, wir haben sie bisher bei fast jedem unserer Stopps entweder f\u00fcr Besorgungen, Stadterkundungen oder f\u00fcr sportliche Touren genutzt. Am zweiten Tag haben wir auch eine Kajaktour, bei einem unendlich chilligen Kajakverleih startend, unternommen. Die Tour kam inmitten des Naturschutzgebiets und mit den sch\u00f6nen Seerosen etc so romantisch daher, entpuppte sich dann aber ganz schnell als fieser Hinterhalt aller Bremsen die Bialowieza zu bieten hatte!! Funktionierender Artenschutz, ough so nervig. Bewirkt hat die Hetzjagd auf uns, dass wir gen\u00f6tigt waren richtig schnell zu paddeln \ud83d\ude00 Ca 30 Bremsen mussten dann aber doch weggeklatscht werden, is wies is. Fazit von Bialowieza: Sch\u00f6nes Naturschutzgebiet, extra nur f\u00fcr den Nationalpark dort hin fahren w\u00fcrde ich pers\u00f6nlich nicht unbedingt, bei einer Durchreise von Polen sollte das aber auf jeden Fall eingeplant werden! ( hallo es gibt dort \u00fcberall Bebistorchis und Bisons) AUSCHWITZ-BIRKENAU Damit komme ich nun aber zu einem sehr d\u00fcsteren Punkt unserer Polendurchquerung, der meiner Meinung nach aber auf jeden Fall zum Pflichtprogramm dazu geh\u00f6rt&#8230; Zumindest dann, wenn man noch nie vorher eine Gedenkst\u00e4tte des Holocausts besucht hat, was zumindest auf mich zutraf. Ich war davor auch leicht nerv\u00f6s, denn es ist klar dass ein Besuch in Auschwitz- Birkenau in jedem Fall belastend wird. Ich habe w\u00e4hrend des 3,5 st\u00fcndigen Rundgangs durch Auschwitz 1 und Auschwitz 2 mehrmals dar\u00fcber nachgedacht, ob wir das als Nachfahren der T\u00e4ter mit einem anderen Blickwinkel des Grauens und der Demut erleben als Menschen anderer Nationalit\u00e4ten. Ich vermute schon. Jedenfalls ging es mir sehr nahe und der Anblick der abertausenden auf gigantischen Bergen gesammelten und ausgestellten Originalgegenst\u00e4nde hinter den Glasfronten der haupts\u00e4chlich J\u00fcdinnen und Juden und der Modellnachbau der Gaskammern und Krematorien war nur sehr schwer zu ertragen. Nat\u00fcrlich hab ich das meiste geschichtliche gewusst, aber manche verst\u00f6rende Details waren dennoch neu f\u00fcr mich. Mir war nicht klar, dass das KL Auschwitz 1 ( also das im Allgemeinen bekannteste KL) wie auf obiger Karte gut sichtbar verh\u00e4ltnism\u00e4\u00dfig klein war. Und das schlimme dabei ist, dass man aber nicht das Gef\u00fchl hat wenn man dort von Block zu Block l\u00e4uft. Es wirkt eher sehr weitl\u00e4ufig und gro\u00df. Dann sieht man dass Auschwitz 2- Birkenau in der N\u00e4he ungef\u00e4hr 20mal so gro\u00df ist. Und man realisiert, dass das gemeinhin bekannte Auschwitz 1 ein Konzentrationslager war, Birkenau jedoch ein reines Vernichtungslager. In beiden KL wurden zwischen 1941 und 1944 1,5 Millionen Menschen ermordet, haupts\u00e4chlich J\u00fcdinnen und Juden aus diesen Teilen Europas. Man erkennt weshalb die Nazis den Ort O\u015bwi\u0119cim gew\u00e4hlt haben. Noch w\u00e4hrend wir an den Ruinen der Gaskammern und Krematorien Birkenaus vorbeilaufen erreicht uns die Nachricht, dass die Auschwitz\u00fcberlebende Esther Bejarano heute mit 96 Jahren gestorben ist und ich glaube trauriger wird es auf unserer Reise nicht mehr. Weiter f\u00fchrt uns unsere Reise in die Slowakei<\/p>\n","protected":false},"author":3,"featured_media":188,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[14,13,15],"class_list":["post-230","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sightseeing","tag-auschwitz","tag-bialowieza","tag-bison"],"_links":{"self":[{"href":"https:\/\/chrassi.de\/index.php\/wp-json\/wp\/v2\/posts\/230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chrassi.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chrassi.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chrassi.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/chrassi.de\/index.php\/wp-json\/wp\/v2\/comments?post=230"}],"version-history":[{"count":10,"href":"https:\/\/chrassi.de\/index.php\/wp-json\/wp\/v2\/posts\/230\/revisions"}],"predecessor-version":[{"id":424,"href":"https:\/\/chrassi.de\/index.php\/wp-json\/wp\/v2\/posts\/230\/revisions\/424"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chrassi.de\/index.php\/wp-json\/wp\/v2\/media\/188"}],"wp:attachment":[{"href":"https:\/\/chrassi.de\/index.php\/wp-json\/wp\/v2\/media?parent=230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chrassi.de\/index.php\/wp-json\/wp\/v2\/categories?post=230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chrassi.de\/index.php\/wp-json\/wp\/v2\/tags?post=230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}